{"id":244600,"date":"2024-04-06T05:25:54","date_gmt":"2024-04-06T10:25:54","guid":{"rendered":"https:\/\/campus.langcom.org\/app\/jobs\/"},"modified":"2026-03-01T06:46:56","modified_gmt":"2026-03-01T11:46:56","slug":"puestos-de-trabajo","status":"publish","type":"page","link":"https:\/\/langcom.edu.pe\/es\/jobs\/","title":{"rendered":"Empleo"},"content":{"rendered":"<div class=\"et_pb_section_0 et_pb_section et_section_regular et_block_section et_pb_section_parallax section_has_divider et_pb_bottom_divider\"><span class=\"et-pb-parallax-wrapper\"><span class=\"et-pb-parallax-background et-pb-parallax-background-module--divi-section-0\" style=\"background-image:url(https:\/\/langcom.org\/wp-content\/uploads\/2026\/02\/marketing-bg6.png)\"><\/span><\/span>\n<div class=\"et_pb_row_0 et_pb_row et_block_row\">\n<div class=\"et_pb_column_0 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_0 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h3>\u00danete a nuestra familia<\/h3>\n<h1>Bolsa de trabajo<\/h1>\n<\/div><\/div>\n\n<div class=\"et_pb_text_1 et_pb_text et_pb_bg_layout_dark et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><p><span>Buscamos a los siguientes profesionales para que se unan a nuestro equipo.<\/span><\/p>\n<\/div><\/div>\n\n<div class=\"et_pb_module et_pb_button_module_wrapper et_pb_button_0_wrapper\"><a class=\"et_pb_button_0 et_pb_button et_pb_bg_layout_dark et_pb_module et_block_module\" href=\"\">Ver funciones abiertas<\/a><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_1 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider\">\n<div class=\"et_pb_row_1 et_pb_row et_block_row\">\n<div class=\"et_pb_column_1 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_2 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h2>Puestos vacantes<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_2 et_pb_row et_pb_gutters2 et_block_row\">\n<div class=\"et_pb_column_2 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_0 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"#top\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue0a1<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"#top\">Profesor de ingl\u00e9s<\/a><\/h4><div class=\"et_pb_blurb_description\"><p>Buscamos profesores de ingl\u00e9s que quieran aplicar la tecnolog\u00eda en sus clases.<\/p>\n<p>Env\u00ede su CV de una p\u00e1gina a <a href=\"mailto:admin@langcom.org\" target=\"_blank\" rel=\"noopener\"><strong>admin@langcom.org<\/strong><\/a><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_3 et_pb_column et_pb_column_1_3 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_1 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"#top\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue0a1<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"#top\">Profesor de espa\u00f1ol<\/a><\/h4><div class=\"et_pb_blurb_description\"><p><span>Buscamos profesores de espa\u00f1ol dispuestos a difundir el uso de esta lengua por todo el mundo.<\/span><\/p>\n<p><span>Env\u00ede su CV de una p\u00e1gina a <a href=\"mailto:admin@langcom.org\" target=\"_blank\" rel=\"noopener\"><strong>admin@langcom.org<\/strong><\/a><\/span><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_4 et_pb_column et_pb_column_1_3 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_2 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_top et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><a href=\"#top\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue08b<\/span><\/span><\/a><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\"><a href=\"#top\">Secretario<\/a><\/h4><div class=\"et_pb_blurb_description\"><p><span>Necesitamos secretaria en Huaraz, Per\u00fa, proactiva, con iniciativa y buen dominio del ingl\u00e9s.<\/span><\/p>\n<p><span>Env\u00ede su CV de una p\u00e1gina a <a href=\"mailto:admin@langcom.org\" target=\"_blank\" rel=\"noopener\"><strong>admin@langcom.org<\/strong><\/a><\/span><\/p>\n<\/div><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>\n\n<div class=\"et_pb_section_2 et_pb_section et_section_regular et_block_section section_has_divider et_pb_bottom_divider\">\n<div class=\"et_pb_row_3 et_pb_row et_block_row\">\n<div class=\"et_pb_column_5 et_pb_column et_pb_column_4_4 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_text_3 et_pb_text et_pb_bg_layout_light et_pb_module et_block_module et_pb_text_align_center\"><div class=\"et_pb_text_inner\"><h2 style=\"background-color: #ffffff; color: #04488b;\">Beneficios<\/h2>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"et_pb_row_4 et_pb_row et_block_row\">\n<div class=\"et_pb_column_6 et_pb_column et_pb_column_1_2 et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_3 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_animated et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">}<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Salario competitivo<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_4 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">T<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Clases gratuitas para familiares directos<\/h4><\/div><\/div><\/div>\n<\/div>\n\n<div class=\"et_pb_column_7 et_pb_column et_pb_column_1_2 et-last-child et_block_column et_pb_css_mix_blend_mode_passthrough\">\n<div class=\"et_pb_blurb_5 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">\ue001<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Bonificaci\u00f3n por excelencia<\/h4><\/div><\/div><\/div>\n\n<div class=\"et_pb_blurb_6 et_pb_blurb et_pb_bg_layout_light et_pb_text_align_center et_pb_blurb_position_left et_pb_module et_block_module\"><div class=\"et_pb_blurb_content\"><div class=\"et_pb_main_blurb_image\"><span class=\"et_pb_image_wrap\"><span class=\"et-pb-icon\">R<\/span><\/span><\/div><div class=\"et_pb_blurb_container\"><h4 class=\"et_pb_module_header\">Formaci\u00f3n continua<\/h4><\/div><\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"et_pb_bottom_inside_divider et-no-transition\"><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"bwfblock_default_font":"","footnotes":""},"class_list":["post-244600","page","type-page","status-publish","hentry"],"dsm_author":{"name":"Ra\u00fal Magui\u00f1a","avatar_url":"https:\/\/cdn.langcom.org\/wp-content\/uploads\/2025\/12\/05230615\/303384a9f021d0f1af05a5f3e1bfaa0b.png","archive_link":"https:\/\/langcom.edu.pe\/es\/author\/langcom\/","biodata":"Ra\u00fal Magui\u00f1a is the Founder and Academic Director of Langcom Academy, an Authorized Cambridge English Preparation Centre and DELE Examination Centre. Over more than 16 years, he has taught students from over 25 countries, coaching candidates to success in Cambridge, IELTS, TOEFL, DELE, SIELE, and Michigan certifications. A certified Cambridge English Speaking Examiner with C2-level mastery credentials (ECPE), he combines rigorous international standards with a warm, fluency-first approach through Langcom's Blended method."},"dsm_categories":[],"dsm_attachment_categories":[],"dsm_featured_image":null,"dsm_comment_count":0,"_links":{"self":[{"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/pages\/244600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/comments?post=244600"}],"version-history":[{"count":0,"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/pages\/244600\/revisions"}],"wp:attachment":[{"href":"https:\/\/langcom.edu.pe\/es\/wp-json\/wp\/v2\/media?parent=244600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}