{"id":168,"count":10,"description":"","link":"https:\/\/langcom.edu.pe\/en\/blog\/category\/learn-english\/english-for-teens-and-adults\/b1-intermediate-english\/","name":"B1 Intermediate English","slug":"b1-intermediate-english","taxonomy":"category","parent":603,"meta":[],"_links":{"self":[{"href":"https:\/\/langcom.edu.pe\/en\/wp-json\/wp\/v2\/categories\/168","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/langcom.edu.pe\/en\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/langcom.edu.pe\/en\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/langcom.edu.pe\/en\/wp-json\/wp\/v2\/categories\/603"}],"wp:post_type":[{"href":"https:\/\/langcom.edu.pe\/en\/wp-json\/wp\/v2\/posts?categories=168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}